{"id":48448,"date":"2023-03-02T19:10:25","date_gmt":"2023-03-02T18:10:25","guid":{"rendered":"https:\/\/www.talleresnasio.com\/uncategorized\/speed-sensor-cable-qst30-cummins-series\/"},"modified":"2025-12-30T19:45:24","modified_gmt":"2025-12-30T18:45:24","slug":"speed-sensor-cable-qst30-cummins-series","status":"publish","type":"product","link":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/","title":{"rendered":"Speed sensor cable QST30 Cummins series"},"content":{"rendered":"<p>&#8211; Genuine Cummins part.||- Cummins 1 year warranty.||- Best quality part guarantee for your engine.||We are Cummins Full Service Dealer. We have a large stock of original Cummins spare parts for your engine. ||The best way to find the right part for your Cummins engine is to have its serial number. This way, we will find the exact part you need.||If you can&#8217;t find the serial number of your Cummins engine, you can&#8217;t find the Cummins product you are looking for, you need information or assistance, contact us. We will be glad to help you.<\/p>\n<p style=\"display: none;\">3408526<\/p>\n<p style=\"display: none;\">9553<\/p>\n<p style=\"display: none;\">dE1JR828CU1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Speed sensor cable QST30 Cummins series. Reference 3408526.<\/p>\n","protected":false},"featured_media":96109,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[606],"product_tag":[],"class_list":{"0":"post-48448","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-engine-spare-parts","8":"first","9":"outofstock","10":"purchasable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Speed sensor cable QST30 Cummins series - Talleres Nasio<\/title>\n<meta name=\"description\" content=\"Speed sensor cable QST30 Cummins series. Reference 3408526.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Speed sensor cable QST30 Cummins series - Talleres Nasio\" \/>\n<meta property=\"og:description\" content=\"Speed sensor cable QST30 Cummins series. Reference 3408526.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/\" \/>\n<meta property=\"og:site_name\" content=\"Talleres Nasio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T18:45:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/cable-sensor-velocidad-serie-qst30-cummins-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/speed-sensor-cable-qst30-cummins-series\\\/\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/speed-sensor-cable-qst30-cummins-series\\\/\",\"name\":\"Speed sensor cable QST30 Cummins series - Talleres Nasio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/speed-sensor-cable-qst30-cummins-series\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/speed-sensor-cable-qst30-cummins-series\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cable-sensor-velocidad-serie-qst30-cummins-.jpg\",\"datePublished\":\"2023-03-02T18:10:25+00:00\",\"dateModified\":\"2025-12-30T18:45:24+00:00\",\"description\":\"Speed sensor cable QST30 Cummins series. Reference 3408526.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/speed-sensor-cable-qst30-cummins-series\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/speed-sensor-cable-qst30-cummins-series\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/speed-sensor-cable-qst30-cummins-series\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cable-sensor-velocidad-serie-qst30-cummins-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cable-sensor-velocidad-serie-qst30-cummins-.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/speed-sensor-cable-qst30-cummins-series\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online Store\",\"item\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Speed sensor cable QST30 Cummins series\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\",\"name\":\"Talleres Nasio\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#organization\",\"name\":\"Talleres Nasio\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-talleres-nasio_vertical.svg\",\"contentUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-talleres-nasio_vertical.svg\",\"width\":110,\"height\":58,\"caption\":\"Talleres Nasio\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Speed sensor cable QST30 Cummins series - Talleres Nasio","description":"Speed sensor cable QST30 Cummins series. Reference 3408526.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Speed sensor cable QST30 Cummins series - Talleres Nasio","og_description":"Speed sensor cable QST30 Cummins series. Reference 3408526.","og_url":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/","og_site_name":"Talleres Nasio","article_modified_time":"2025-12-30T18:45:24+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/cable-sensor-velocidad-serie-qst30-cummins-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/","url":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/","name":"Speed sensor cable QST30 Cummins series - Talleres Nasio","isPartOf":{"@id":"https:\/\/www.talleresnasio.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/#primaryimage"},"image":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/#primaryimage"},"thumbnailUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/cable-sensor-velocidad-serie-qst30-cummins-.jpg","datePublished":"2023-03-02T18:10:25+00:00","dateModified":"2025-12-30T18:45:24+00:00","description":"Speed sensor cable QST30 Cummins series. Reference 3408526.","breadcrumb":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/#primaryimage","url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/cable-sensor-velocidad-serie-qst30-cummins-.jpg","contentUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/cable-sensor-velocidad-serie-qst30-cummins-.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/speed-sensor-cable-qst30-cummins-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.talleresnasio.com\/en\/"},{"@type":"ListItem","position":2,"name":"Online Store","item":"https:\/\/www.talleresnasio.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Speed sensor cable QST30 Cummins series"}]},{"@type":"WebSite","@id":"https:\/\/www.talleresnasio.com\/en\/#website","url":"https:\/\/www.talleresnasio.com\/en\/","name":"Talleres Nasio","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.talleresnasio.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.talleresnasio.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.talleresnasio.com\/en\/#organization","name":"Talleres Nasio","url":"https:\/\/www.talleresnasio.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.talleresnasio.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/05\/logo-talleres-nasio_vertical.svg","contentUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/05\/logo-talleres-nasio_vertical.svg","width":110,"height":58,"caption":"Talleres Nasio"},"image":{"@id":"https:\/\/www.talleresnasio.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product\/48448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/comments?post=48448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/media\/96109"}],"wp:attachment":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/media?parent=48448"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_brand?post=48448"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_cat?post=48448"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_tag?post=48448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}