{"id":48275,"date":"2023-03-02T19:06:59","date_gmt":"2023-03-02T18:06:59","guid":{"rendered":"https:\/\/www.talleresnasio.com\/uncategorized\/cummins-k38-series-lower-part-gasket-set\/"},"modified":"2025-12-30T19:42:19","modified_gmt":"2025-12-30T18:42:19","slug":"cummins-k38-series-lower-part-gasket-set","status":"publish","type":"product","link":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/","title":{"rendered":"Cummins K38 series lower part gasket set"},"content":{"rendered":"<p>&#8211; Genuine Cummins part.||- Cummins 1 year warranty.||- Best quality part guarantee for your engine.||We are Cummins Full Service Dealer. We have a large stock of original Cummins spare parts for your engine. ||The best way to find the right part for your Cummins engine is to have its serial number. This way, we will find the exact part you need. ||How to physically find the Cummins Engine Identification Number or Engine Serial Number (EIN or ESN) on the dataplate of your Cummins engine: To identify the serial number of your Cummins engine, look on the engine dataplate. The official Cummins term for identifying the serial number of a Cummins engine is ESN. The serial number is the number that appears behind: ESN, SN, Engine Number, Engine No &#8230; And it is always composed by 8 numbers, it never has letters.||On electronic engines the serial number can be found on the dataplate of the electronic control unit of the engine. ||If you can&#8217;t find the serial number of your Cummins engine, you can&#8217;t find the Cummins product you are looking for, you need information or assistance, contact us. We will be glad to help you.<\/p>\n<p style=\"display: none;\">4956090<\/p>\n<p style=\"display: none;\">2619<\/p>\n<p style=\"display: none;\">dE18x0N3CU1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cummins K38 series lower part gasket set. Reference 4956090.<\/p>\n","protected":false},"featured_media":33139,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[606],"product_tag":[],"class_list":{"0":"post-48275","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-engine-spare-parts","8":"first","9":"outofstock","10":"purchasable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cummins K38 series lower part gasket set - Talleres Nasio<\/title>\n<meta name=\"description\" content=\"Cummins K38 series lower part gasket set. Reference 4956090.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cummins K38 series lower part gasket set - Talleres Nasio\" \/>\n<meta property=\"og:description\" content=\"Cummins K38 series lower part gasket set. Reference 4956090.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/\" \/>\n<meta property=\"og:site_name\" content=\"Talleres Nasio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T18:42:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/09\/juego-juntas-parte-baja-serie-k38-cummins-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k38-series-lower-part-gasket-set\\\/\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k38-series-lower-part-gasket-set\\\/\",\"name\":\"Cummins K38 series lower part gasket set - Talleres Nasio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k38-series-lower-part-gasket-set\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k38-series-lower-part-gasket-set\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/juego-juntas-parte-baja-serie-k38-cummins-1.jpg\",\"datePublished\":\"2023-03-02T18:06:59+00:00\",\"dateModified\":\"2025-12-30T18:42:19+00:00\",\"description\":\"Cummins K38 series lower part gasket set. Reference 4956090.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k38-series-lower-part-gasket-set\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k38-series-lower-part-gasket-set\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k38-series-lower-part-gasket-set\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/juego-juntas-parte-baja-serie-k38-cummins-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/juego-juntas-parte-baja-serie-k38-cummins-1.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k38-series-lower-part-gasket-set\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online Store\",\"item\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cummins K38 series lower part gasket set\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\",\"name\":\"Talleres Nasio\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#organization\",\"name\":\"Talleres Nasio\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-talleres-nasio_vertical.svg\",\"contentUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-talleres-nasio_vertical.svg\",\"width\":110,\"height\":58,\"caption\":\"Talleres Nasio\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cummins K38 series lower part gasket set - Talleres Nasio","description":"Cummins K38 series lower part gasket set. Reference 4956090.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Cummins K38 series lower part gasket set - Talleres Nasio","og_description":"Cummins K38 series lower part gasket set. Reference 4956090.","og_url":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/","og_site_name":"Talleres Nasio","article_modified_time":"2025-12-30T18:42:19+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/09\/juego-juntas-parte-baja-serie-k38-cummins-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/","url":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/","name":"Cummins K38 series lower part gasket set - Talleres Nasio","isPartOf":{"@id":"https:\/\/www.talleresnasio.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/#primaryimage"},"image":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/#primaryimage"},"thumbnailUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/09\/juego-juntas-parte-baja-serie-k38-cummins-1.jpg","datePublished":"2023-03-02T18:06:59+00:00","dateModified":"2025-12-30T18:42:19+00:00","description":"Cummins K38 series lower part gasket set. Reference 4956090.","breadcrumb":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/#primaryimage","url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/09\/juego-juntas-parte-baja-serie-k38-cummins-1.jpg","contentUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/09\/juego-juntas-parte-baja-serie-k38-cummins-1.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k38-series-lower-part-gasket-set\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.talleresnasio.com\/en\/"},{"@type":"ListItem","position":2,"name":"Online Store","item":"https:\/\/www.talleresnasio.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Cummins K38 series lower part gasket set"}]},{"@type":"WebSite","@id":"https:\/\/www.talleresnasio.com\/en\/#website","url":"https:\/\/www.talleresnasio.com\/en\/","name":"Talleres Nasio","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.talleresnasio.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.talleresnasio.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.talleresnasio.com\/en\/#organization","name":"Talleres Nasio","url":"https:\/\/www.talleresnasio.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.talleresnasio.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/05\/logo-talleres-nasio_vertical.svg","contentUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/05\/logo-talleres-nasio_vertical.svg","width":110,"height":58,"caption":"Talleres Nasio"},"image":{"@id":"https:\/\/www.talleresnasio.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product\/48275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/comments?post=48275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/media\/33139"}],"wp:attachment":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/media?parent=48275"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_brand?post=48275"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_cat?post=48275"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_tag?post=48275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}