{"id":47374,"date":"2023-03-02T18:54:56","date_gmt":"2023-03-02T17:54:56","guid":{"rendered":"https:\/\/www.talleresnasio.com\/uncategorized\/cummins-c-series-salt-water-cooler-outlet-elbow\/"},"modified":"2025-12-30T19:28:34","modified_gmt":"2025-12-30T18:28:34","slug":"cummins-c-series-salt-water-cooler-outlet-elbow","status":"publish","type":"product","link":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/","title":{"rendered":"Cummins C series salt water cooler outlet elbow"},"content":{"rendered":"<p>&#8211; Genuine Cummins part.||- Cummins 1 year warranty.||- Best quality part guarantee for your engine.||We are Cummins Full Service Dealer. We have a large stock of original Cummins spare parts for your engine. ||The best way to find the right part for your Cummins engine is to have its serial number. This way, we will find the exact part you need. If you can&#8217;t find the serial number of your Cummins engine, you can&#8217;t find the Cummins product you are looking for, you need information or assistance, contact us. We will be glad to help you.<\/p>\n<p style=\"display: none;\">3912177<\/p>\n<p style=\"display: none;\">5122<\/p>\n<p style=\"display: none;\">d1969002CU1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cummins C series salt water cooler outlet elbow. Reference Cummins 3912177.<\/p>\n","protected":false},"featured_media":128483,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[606],"product_tag":[],"class_list":{"0":"post-47374","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-engine-spare-parts","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cummins C series salt water cooler outlet elbow - Talleres Nasio<\/title>\n<meta name=\"description\" content=\"Cummins C series salt water cooler outlet elbow. Reference Cummins 3912177.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cummins C series salt water cooler outlet elbow - Talleres Nasio\" \/>\n<meta property=\"og:description\" content=\"Cummins C series salt water cooler outlet elbow. Reference Cummins 3912177.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/\" \/>\n<meta property=\"og:site_name\" content=\"Talleres Nasio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T18:28:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/codo-salida-enfriador-agua-salada-serie-c-cummins-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-c-series-salt-water-cooler-outlet-elbow\\\/\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-c-series-salt-water-cooler-outlet-elbow\\\/\",\"name\":\"Cummins C series salt water cooler outlet elbow - Talleres Nasio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-c-series-salt-water-cooler-outlet-elbow\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-c-series-salt-water-cooler-outlet-elbow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/codo-salida-enfriador-agua-salada-serie-c-cummins-1.jpg\",\"datePublished\":\"2023-03-02T17:54:56+00:00\",\"dateModified\":\"2025-12-30T18:28:34+00:00\",\"description\":\"Cummins C series salt water cooler outlet elbow. Reference Cummins 3912177.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-c-series-salt-water-cooler-outlet-elbow\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-c-series-salt-water-cooler-outlet-elbow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-c-series-salt-water-cooler-outlet-elbow\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/codo-salida-enfriador-agua-salada-serie-c-cummins-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/codo-salida-enfriador-agua-salada-serie-c-cummins-1.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-c-series-salt-water-cooler-outlet-elbow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online Store\",\"item\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cummins C series salt water cooler outlet elbow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\",\"name\":\"Talleres Nasio\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#organization\",\"name\":\"Talleres Nasio\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-talleres-nasio_vertical.svg\",\"contentUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-talleres-nasio_vertical.svg\",\"width\":110,\"height\":58,\"caption\":\"Talleres Nasio\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cummins C series salt water cooler outlet elbow - Talleres Nasio","description":"Cummins C series salt water cooler outlet elbow. Reference Cummins 3912177.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Cummins C series salt water cooler outlet elbow - Talleres Nasio","og_description":"Cummins C series salt water cooler outlet elbow. Reference Cummins 3912177.","og_url":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/","og_site_name":"Talleres Nasio","article_modified_time":"2025-12-30T18:28:34+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/codo-salida-enfriador-agua-salada-serie-c-cummins-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/","url":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/","name":"Cummins C series salt water cooler outlet elbow - Talleres Nasio","isPartOf":{"@id":"https:\/\/www.talleresnasio.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/#primaryimage"},"image":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/#primaryimage"},"thumbnailUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/codo-salida-enfriador-agua-salada-serie-c-cummins-1.jpg","datePublished":"2023-03-02T17:54:56+00:00","dateModified":"2025-12-30T18:28:34+00:00","description":"Cummins C series salt water cooler outlet elbow. Reference Cummins 3912177.","breadcrumb":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/#primaryimage","url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/codo-salida-enfriador-agua-salada-serie-c-cummins-1.jpg","contentUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/codo-salida-enfriador-agua-salada-serie-c-cummins-1.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-c-series-salt-water-cooler-outlet-elbow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.talleresnasio.com\/en\/"},{"@type":"ListItem","position":2,"name":"Online Store","item":"https:\/\/www.talleresnasio.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Cummins C series salt water cooler outlet elbow"}]},{"@type":"WebSite","@id":"https:\/\/www.talleresnasio.com\/en\/#website","url":"https:\/\/www.talleresnasio.com\/en\/","name":"Talleres Nasio","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.talleresnasio.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.talleresnasio.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.talleresnasio.com\/en\/#organization","name":"Talleres Nasio","url":"https:\/\/www.talleresnasio.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.talleresnasio.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/05\/logo-talleres-nasio_vertical.svg","contentUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/05\/logo-talleres-nasio_vertical.svg","width":110,"height":58,"caption":"Talleres Nasio"},"image":{"@id":"https:\/\/www.talleresnasio.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product\/47374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/comments?post=47374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/media\/128483"}],"wp:attachment":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/media?parent=47374"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_brand?post=47374"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_cat?post=47374"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_tag?post=47374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}