{"id":47164,"date":"2023-03-02T18:52:12","date_gmt":"2023-03-02T17:52:12","guid":{"rendered":"https:\/\/www.talleresnasio.com\/uncategorized\/cummins-k19-series-side-cover-seal\/"},"modified":"2025-12-30T19:24:58","modified_gmt":"2025-12-30T18:24:58","slug":"cummins-k19-series-side-cover-seal","status":"publish","type":"product","link":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/","title":{"rendered":"Cummins K19 series side cover seal"},"content":{"rendered":"<p>&#8211; Genuine Cummins part.||- Cummins 1 year warranty.||- Best quality part guarantee for your engine.||We are Cummins Full Service Dealer. We have a large stock of original Cummins spare parts for your engine. ||The best way to find the right part for your Cummins engine is to have its serial number. This way, we will find the exact part you need. If you can&#8217;t find the serial number of your Cummins engine, you can&#8217;t find the Cummins product you are looking for, you need information or assistance, contact us. We will be glad to help you.<\/p>\n<p style=\"display: none;\">3042586<\/p>\n<p style=\"display: none;\">2884<\/p>\n<p style=\"display: none;\">dD65703VCU1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cummins K19 series side cover seal. Reference 3042586.<\/p>\n","protected":false},"featured_media":72194,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[606],"product_tag":[],"class_list":{"0":"post-47164","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-engine-spare-parts","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cummins K19 series side cover seal - Talleres Nasio<\/title>\n<meta name=\"description\" content=\"Cummins K19 series side cover seal. Reference 3042586.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cummins K19 series side cover seal - Talleres Nasio\" \/>\n<meta property=\"og:description\" content=\"Cummins K19 series side cover seal. Reference 3042586.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/\" \/>\n<meta property=\"og:site_name\" content=\"Talleres Nasio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T18:24:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/junta-tapa-lateral-sobrecarter-serie-k19-cummins-jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k19-series-side-cover-seal\\\/\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k19-series-side-cover-seal\\\/\",\"name\":\"Cummins K19 series side cover seal - Talleres Nasio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k19-series-side-cover-seal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k19-series-side-cover-seal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/junta-tapa-lateral-sobrecarter-serie-k19-cummins-jpg.jpg\",\"datePublished\":\"2023-03-02T17:52:12+00:00\",\"dateModified\":\"2025-12-30T18:24:58+00:00\",\"description\":\"Cummins K19 series side cover seal. Reference 3042586.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k19-series-side-cover-seal\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k19-series-side-cover-seal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k19-series-side-cover-seal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/junta-tapa-lateral-sobrecarter-serie-k19-cummins-jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/junta-tapa-lateral-sobrecarter-serie-k19-cummins-jpg.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/engine\\\/engine-spare-parts\\\/cummins-k19-series-side-cover-seal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online Store\",\"item\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cummins K19 series side cover seal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\",\"name\":\"Talleres Nasio\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#organization\",\"name\":\"Talleres Nasio\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-talleres-nasio_vertical.svg\",\"contentUrl\":\"https:\\\/\\\/www.talleresnasio.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-talleres-nasio_vertical.svg\",\"width\":110,\"height\":58,\"caption\":\"Talleres Nasio\"},\"image\":{\"@id\":\"https:\\\/\\\/www.talleresnasio.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cummins K19 series side cover seal - Talleres Nasio","description":"Cummins K19 series side cover seal. Reference 3042586.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Cummins K19 series side cover seal - Talleres Nasio","og_description":"Cummins K19 series side cover seal. Reference 3042586.","og_url":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/","og_site_name":"Talleres Nasio","article_modified_time":"2025-12-30T18:24:58+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/junta-tapa-lateral-sobrecarter-serie-k19-cummins-jpg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/","url":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/","name":"Cummins K19 series side cover seal - Talleres Nasio","isPartOf":{"@id":"https:\/\/www.talleresnasio.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/#primaryimage"},"image":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/junta-tapa-lateral-sobrecarter-serie-k19-cummins-jpg.jpg","datePublished":"2023-03-02T17:52:12+00:00","dateModified":"2025-12-30T18:24:58+00:00","description":"Cummins K19 series side cover seal. Reference 3042586.","breadcrumb":{"@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/#primaryimage","url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/junta-tapa-lateral-sobrecarter-serie-k19-cummins-jpg.jpg","contentUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2023\/03\/junta-tapa-lateral-sobrecarter-serie-k19-cummins-jpg.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.talleresnasio.com\/en\/engine\/engine-spare-parts\/cummins-k19-series-side-cover-seal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.talleresnasio.com\/en\/"},{"@type":"ListItem","position":2,"name":"Online Store","item":"https:\/\/www.talleresnasio.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Cummins K19 series side cover seal"}]},{"@type":"WebSite","@id":"https:\/\/www.talleresnasio.com\/en\/#website","url":"https:\/\/www.talleresnasio.com\/en\/","name":"Talleres Nasio","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.talleresnasio.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.talleresnasio.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.talleresnasio.com\/en\/#organization","name":"Talleres Nasio","url":"https:\/\/www.talleresnasio.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.talleresnasio.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/05\/logo-talleres-nasio_vertical.svg","contentUrl":"https:\/\/www.talleresnasio.com\/wp-content\/uploads\/2022\/05\/logo-talleres-nasio_vertical.svg","width":110,"height":58,"caption":"Talleres Nasio"},"image":{"@id":"https:\/\/www.talleresnasio.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product\/47164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/comments?post=47164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/media\/72194"}],"wp:attachment":[{"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/media?parent=47164"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_brand?post=47164"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_cat?post=47164"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.talleresnasio.com\/en\/wp-json\/wp\/v2\/product_tag?post=47164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}